{"id":5097,"date":"2024-02-02T14:40:32","date_gmt":"2024-02-02T13:40:32","guid":{"rendered":"https:\/\/www.lkeria.com\/actualites\/non-classe\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/"},"modified":"2024-02-02T14:40:34","modified_gmt":"2024-02-02T13:40:34","slug":"les-constructions-illicites-en-algerie-deux-poids-deux-mesures","status":"publish","type":"post","link":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/","title":{"rendered":"Constructions illicites : deux poids deux mesures"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><a href=\"https:\/\/www.lkeria.com\/wp-content\/uploads\/2011\/08\/2pois2mesures-algerie.jpg\"><img decoding=\"async\" src=\"https:\/\/www.lkeria.com\/wp-content\/uploads\/2011\/08\/2pois2mesures-algerie-150x150.jpg\" alt=\"construction illicite en algerie\" class=\"wp-image-867\"\/><\/a><\/figure>\n<\/div>\n\n\n<p>Maroua est d\u00e9c\u00e9d\u00e9e et ses parents sont entre la vie et la mort qu&rsquo;ils ont tous deux souhait\u00e9. Le p\u00e8re et la m\u00e8re de Meroua se sont immol\u00e9s avec elle devant le si\u00e8ge de l\u2019APC afin que le pr\u00e9sident de l\u2019APC, qui a d\u00e9moli leur gourbi consid\u00e9r\u00e9 comme constructions illicites, puisse les voir, eux, qu&rsquo;il a d\u00e9ni\u00e9 de recevoir avant qu\u2019ils ne soient flamb\u00e9s.<\/p>\n\n\n\n<p>On d\u00e9truit les constructions illicites des mis\u00e9reux qui b\u00e2tissent des\u00a0maisons de fortune et on laisse les plus riche construire illicitement mais en toute tranquillit\u00e9 villa, immeubles ch\u00e2teaux et usines et nombreux parmi ces supers citoyens sont ceux cens\u00e9s faire appliquer et respecter la loi.<\/p>\n\n\n\n<p>Quelle diff\u00e9rence y a t-il entre une <a href=\"https:\/\/www.lkeria.com\/annonces\/immobilier\/vente\/villa\">villa, un immeuble, un bungalow<\/a>, un complexe ou une usine \u00e9rig\u00e9e sans permis de construire et une baraque sans papier ?<\/p>\n\n\n\n<p>La petite fille Maroua ne comprendra donc jamais pourquoi ses parents ont v\u00e9cu pauvres dans un pays hyper riche. Elle n\u2019ira \u00e9galement pas \u00e0 l&rsquo;\u00e9cole et le ministre de la solidarit\u00e9 n&rsquo;aura pas la chance de la comptabiliser comme \u00e9tant un cartable de plus dans sa liste qu&rsquo;il \u00e9talera avec arrogance devant la <a href=\"https:\/\/medias-dz.com\/television\/\">cam\u00e9ra de la T\u00e9l\u00e9vision.<\/a><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>L\u2019adage dit <strong>\u00ab&nbsp;la loi, c&rsquo;est comme une toile d&rsquo;araign\u00e9e, elle ne retient que les petits insectes&nbsp;\u00bb<\/strong>.<\/p>\n<\/blockquote>\n\n\n\n<p>La petite Meroua ira au paradis, l\u00e0 o\u00f9 ceux qui ont appauvri ses parents n&rsquo;y mettront jamais les pieds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maroua est d\u00e9c\u00e9d\u00e9e et ses parents sont entre la vie et la mort qu&rsquo;ils ont tous deux souhait\u00e9. Le p\u00e8re et la m\u00e8re de Meroua se sont immol\u00e9s avec elle devant le si\u00e8ge de l\u2019APC afin que le pr\u00e9sident de l\u2019APC, qui a d\u00e9moli leur gourbi consid\u00e9r\u00e9 comme constructions illicites, puisse les voir, eux, qu&rsquo;il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229],"tags":[],"class_list":["post-5097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constructions illicites : deux poids deux mesures<\/title>\n<meta name=\"description\" content=\"On d\u00e9truit les constructions illicites des mis\u00e9reux qui b\u00e2tissent des maisons de fortune et on laisse les plus riche construire illicitement\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constructions illicites : deux poids deux mesures\" \/>\n<meta property=\"og:description\" content=\"On d\u00e9truit les constructions illicites des mis\u00e9reux qui b\u00e2tissent des maisons de fortune et on laisse les plus riche construire illicitement\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lkeriacom\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-02T13:40:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T13:40:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2022\/12\/demolition.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"847\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lotfi Ramdani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lkeriacom\" \/>\n<meta name=\"twitter:site\" content=\"@lkeriacom\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lotfi Ramdani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constructions illicites : deux poids deux mesures","description":"On d\u00e9truit les constructions illicites des mis\u00e9reux qui b\u00e2tissent des maisons de fortune et on laisse les plus riche construire illicitement","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/","og_locale":"fr_FR","og_type":"article","og_title":"Constructions illicites : deux poids deux mesures","og_description":"On d\u00e9truit les constructions illicites des mis\u00e9reux qui b\u00e2tissent des maisons de fortune et on laisse les plus riche construire illicitement","og_url":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/","og_site_name":"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","article_publisher":"https:\/\/www.facebook.com\/lkeriacom","article_published_time":"2024-02-02T13:40:32+00:00","article_modified_time":"2024-02-02T13:40:34+00:00","og_image":[{"width":847,"height":565,"url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2022\/12\/demolition.jpg","type":"image\/jpeg"}],"author":"Lotfi Ramdani","twitter_card":"summary_large_image","twitter_creator":"@lkeriacom","twitter_site":"@lkeriacom","twitter_misc":{"\u00c9crit par":"Lotfi Ramdani","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#article","isPartOf":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/"},"author":{"name":"Lotfi Ramdani","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/person\/3a4da2e91b49098351a6c1a04c231e06"},"headline":"Constructions illicites : deux poids deux mesures","datePublished":"2024-02-02T13:40:32+00:00","dateModified":"2024-02-02T13:40:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/"},"wordCount":272,"publisher":{"@id":"https:\/\/www.lkeria.com\/actualites\/#organization"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2022\/12\/demolition.jpg","articleSection":["Logement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/","url":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/","name":"Constructions illicites : deux poids deux mesures","isPartOf":{"@id":"https:\/\/www.lkeria.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#primaryimage"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2022\/12\/demolition.jpg","datePublished":"2024-02-02T13:40:32+00:00","dateModified":"2024-02-02T13:40:34+00:00","description":"On d\u00e9truit les constructions illicites des mis\u00e9reux qui b\u00e2tissent des maisons de fortune et on laisse les plus riche construire illicitement","breadcrumb":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#primaryimage","url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2022\/12\/demolition.jpg","contentUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2022\/12\/demolition.jpg","width":847,"height":565,"caption":"Worker with personal protection equipment and demolition hammer at service for interior brick wall construction breaking in building industry"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/les-constructions-illicites-en-algerie-deux-poids-deux-mesures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lkeria.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Constructions illicites : deux poids deux mesures"}]},{"@type":"WebSite","@id":"https:\/\/www.lkeria.com\/actualites\/#website","url":"https:\/\/www.lkeria.com\/actualites\/","name":"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","description":"logement et annonces immobili\u00e8res","publisher":{"@id":"https:\/\/www.lkeria.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lkeria.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lkeria.com\/actualites\/#organization","name":"Lkeria","url":"https:\/\/www.lkeria.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2020\/07\/logo-lkeria.png","contentUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2020\/07\/logo-lkeria.png","width":200,"height":72,"caption":"Lkeria"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lkeriacom","https:\/\/x.com\/lkeriacom"]},{"@type":"Person","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/person\/3a4da2e91b49098351a6c1a04c231e06","name":"Lotfi Ramdani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"Lotfi Ramdani"},"url":"https:\/\/www.lkeria.com\/actualites\/author\/chakib32gmail-com\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/5097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/comments?post=5097"}],"version-history":[{"count":3,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/5097\/revisions"}],"predecessor-version":[{"id":7222,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/5097\/revisions\/7222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/media\/6375"}],"wp:attachment":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/media?parent=5097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/categories?post=5097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/tags?post=5097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}