{"id":4970,"date":"2012-11-19T23:13:36","date_gmt":"2012-11-19T22:13:36","guid":{"rendered":"https:\/\/www.lkeria.com\/actualites\/non-classe\/sidi-bel-abbes-habitations-intemperies\/"},"modified":"2012-11-19T23:13:36","modified_gmt":"2012-11-19T22:13:36","slug":"sidi-bel-abbes-habitations-intemperies","status":"publish","type":"post","link":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/","title":{"rendered":"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali"},"content":{"rendered":"<div id=\"attachment_761\" style=\"width: 160px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes.jpg\"><img aria-describedby=\"caption-attachment-761\" class=\"size-thumbnail wp-image-761\"[caption id=\"attachment_761\" align=\"alignleft\" width=\"150\"]<a href=\"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes.jpg\"><p id=\"caption-attachment-761\" class=\"wp-caption-text\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-761\" alt=\"logement sidi bel abes\" src=\"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg\" width=\"150\" height=\"150\" \/><\/a> Sidi Bel Abb\u00e8s : Leurs Habitations \u00c9tant Endommag\u00e9es Par Les Intemp\u00e9ries. Des Citoyens Interpellent Le Wali<\/p><\/div>\n<p style=\"text-align: justify;\">Depuis les derni\u00e8res intemp\u00e9ries, les habitants des 40 et 122 logements dans la da\u00efra de Mostafa Ben Brahim, ne cessent de frapper aux portes des responsables de leur da\u00efra, dans l\u2019espoir de trouver une quelconque solution \u00e0 leur situation. Selon ces citoyens, leurs habitations v\u00e9tustes ont \u00e9t\u00e9 partiellement d\u00e9molies par les fortes averses qui se sont abattues sur la wilaya.<\/p>\n<p style=\"text-align: justify;\">Depuis, ils ne trouvent plus o\u00f9 s\u2019abriter. A ce sujet, ils soutiennent qu\u2019ils ont couvert les toits de b\u00e2ches en plastique mais l\u2019eau s\u2019y est infiltr\u00e9e, alors que d\u2019autres ont squatt\u00e9 des appartements r\u00e9alis\u00e9s dans le cadre du LSP et ont \u00e9t\u00e9 expuls\u00e9s par les services de s\u00e9curit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Ils indiquent que l\u2019\u00e9tat lamentable des logements ne les encourage pas \u00e0 y retourner, alors qu\u2019ils n\u2019ont plus o\u00f9 habiter. M\u00eame situation que vivent 14 familles occupant une maison collective dans le quartier Sidi Yacine, qui ont lanc\u00e9 un appel aux autorit\u00e9s locales pour les reloger dans les brefs d\u00e9lais.<\/p>\n<p style=\"text-align: justify;\">Leurs pi\u00e8ces ont \u00e9t\u00e9 endommag\u00e9es, indiquent-elles, \u00e0 cause des intemp\u00e9ries, et risquent de s\u2019effondrer. Les eaux de pluies ont inond\u00e9 les pi\u00e8ces qui datent de l\u2019\u00e8re coloniale et les ont d\u00e9t\u00e9rior\u00e9es. Les sinistr\u00e9s des averses vivent la peur dans le ventre de mourir sous les d\u00e9combres et sollicitent le premier responsable de la wilaya, \u00e0 intervenir pour leur relogement dans des \u00a0appartements d\u00e9cents, indiquant qu\u2019ils avaient fait l\u2019objet de recensement parmi les habitants du pr\u00e9caire.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/plus.google.com\/105012336724312757634?rel=author\">Lotfi Ramdani<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis les derni\u00e8res intemp\u00e9ries, les habitants des 40 et 122 logements dans la da\u00efra de Mostafa Ben Brahim, ne cessent de frapper aux portes des responsables de leur da\u00efra, dans l\u2019espoir de trouver une quelconque solution \u00e0 leur situation. Selon ces citoyens, leurs habitations v\u00e9tustes ont \u00e9t\u00e9 partiellement d\u00e9molies par les fortes averses qui se [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229],"tags":[],"class_list":["post-4970","post","type-post","status-publish","format-standard","hentry","category-logement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie\" \/>\n<meta property=\"og:description\" content=\"Depuis les derni\u00e8res intemp\u00e9ries, les habitants des 40 et 122 logements dans la da\u00efra de Mostafa Ben Brahim, ne cessent de frapper aux portes des responsables de leur da\u00efra, dans l\u2019espoir de trouver une quelconque solution \u00e0 leur situation. Selon ces citoyens, leurs habitations v\u00e9tustes ont \u00e9t\u00e9 partiellement d\u00e9molies par les fortes averses qui se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lkeriacom\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-19T22:13:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg\" \/>\n<meta name=\"author\" content=\"Lotfi Ramdani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lkeriacom\" \/>\n<meta name=\"twitter:site\" content=\"@lkeriacom\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lotfi Ramdani\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/","og_locale":"fr_FR","og_type":"article","og_title":"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","og_description":"Depuis les derni\u00e8res intemp\u00e9ries, les habitants des 40 et 122 logements dans la da\u00efra de Mostafa Ben Brahim, ne cessent de frapper aux portes des responsables de leur da\u00efra, dans l\u2019espoir de trouver une quelconque solution \u00e0 leur situation. Selon ces citoyens, leurs habitations v\u00e9tustes ont \u00e9t\u00e9 partiellement d\u00e9molies par les fortes averses qui se [&hellip;]","og_url":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/","og_site_name":"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","article_publisher":"https:\/\/www.facebook.com\/lkeriacom","article_published_time":"2012-11-19T22:13:36+00:00","og_image":[{"url":"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg","type":"","width":"","height":""}],"author":"Lotfi Ramdani","twitter_card":"summary_large_image","twitter_creator":"@lkeriacom","twitter_site":"@lkeriacom","twitter_misc":{"\u00c9crit par":"Lotfi Ramdani"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#article","isPartOf":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/"},"author":{"name":"Lotfi Ramdani","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/person\/3a4da2e91b49098351a6c1a04c231e06"},"headline":"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali","datePublished":"2012-11-19T22:13:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/"},"wordCount":24,"publisher":{"@id":"https:\/\/www.lkeria.com\/actualites\/#organization"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg","articleSection":["Logement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/","url":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/","name":"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","isPartOf":{"@id":"https:\/\/www.lkeria.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#primaryimage"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg","datePublished":"2012-11-19T22:13:36+00:00","breadcrumb":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#primaryimage","url":"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg","contentUrl":"https:\/\/www.lkeria.com\/wp-content\/uploads\/2012\/11\/innondations-sidibel-abbes-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/sidi-bel-abbes-habitations-intemperies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lkeria.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Sidi Bel Abb\u00e8s : Leurs habitations \u00e9tant endommag\u00e9es par les intemp\u00e9ries. Des citoyens interpellent le wali"}]},{"@type":"WebSite","@id":"https:\/\/www.lkeria.com\/actualites\/#website","url":"https:\/\/www.lkeria.com\/actualites\/","name":"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","description":"logement et annonces immobili\u00e8res","publisher":{"@id":"https:\/\/www.lkeria.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lkeria.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lkeria.com\/actualites\/#organization","name":"Lkeria","url":"https:\/\/www.lkeria.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2020\/07\/logo-lkeria.png","contentUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2020\/07\/logo-lkeria.png","width":200,"height":72,"caption":"Lkeria"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lkeriacom","https:\/\/x.com\/lkeriacom"]},{"@type":"Person","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/person\/3a4da2e91b49098351a6c1a04c231e06","name":"Lotfi Ramdani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"Lotfi Ramdani"},"url":"https:\/\/www.lkeria.com\/actualites\/author\/chakib32gmail-com\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/4970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/comments?post=4970"}],"version-history":[{"count":0,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/4970\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/media?parent=4970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/categories?post=4970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/tags?post=4970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}