{"id":4966,"date":"2013-01-04T18:44:06","date_gmt":"2013-01-04T17:44:06","guid":{"rendered":"https:\/\/www.lkeria.com\/actualites\/non-classe\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/"},"modified":"2021-09-25T20:03:11","modified_gmt":"2021-09-25T18:03:11","slug":"arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition","status":"publish","type":"post","link":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/","title":{"rendered":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements"},"content":{"rendered":"\n<p>La ville <strong>d\u2019Arzew<\/strong> \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux. C\u2019\u00e9tait le sujet principal de toute discussion entre les citoyens, notamment ceux ; qui ont d\u00e9pos\u00e9 des dossiers pour pr\u00e9tendre \u00e0 un toit d\u00e9cent dans le cadre du programme au relogement social.<\/p>\n\n\n\n<p>Selon certaines sources dignes de foi, cette premi\u00e8re tranche de logements sociaux, dont les dossiers\u00a0; des postulants ont \u00e9t\u00e9 trait\u00e9s par la commission d\u2019\u00e9tude et de distribution des logements ; se compose de 850 unit\u00e9s en cours de construction au niveau de la localit\u00e9 d\u2019El Mohgoun et plus pr\u00e9cis\u00e9ment en face de l\u2019h\u00f4pital Nekkache.<\/p>\n\n\n\n<p>Le second quota de 250 logements, situ\u00e9 au niveau de Hai Gourine, en voie de finition et destin\u00e9 ; aux occupants des caves et autres de l\u2019habitat pr\u00e9caire sera livr\u00e9 et attribu\u00e9 au plus tard dans un mois.\u00a0Enfin, la derni\u00e8re tranche de ce programme, compos\u00e9e de 200 unit\u00e9s ; situ\u00e9e \u00e0 la sortie d\u2019El Mohgoun,\u00a0est achev\u00e9e et r\u00e9ceptionn\u00e9e et pr\u00eate \u00e0 \u00eatre livr\u00e9e.<\/p>\n\n\n\n<p>Ces habitations, selon notre source, reviennent aux occupants du site appel\u00e9 \u00ab Cr\u00e8che \u00bb ; l\u2019ancienne caserne des pompiers, des baraques du jardin public, de la vieille mosqu\u00e9e de la cit\u00e9 du \u00abcomplexe\u00bb ; du vieux b\u00e2ti et de diff\u00e9rentes zones \u00e9parses. Des affectations de logements des deux derni\u00e8res tranches de 250 et 200 unit\u00e9s sociales seront attribu\u00e9es dans l\u2019imm\u00e9diat.<\/p>\n\n\n\n<p>Dans une ambiance calme et sereine, \u00e0 part quelques revendications un peu bruyantes ; de certains groupuscules insatisfaits, les personnes se sentant l\u00e9s\u00e9es et non port\u00e9es sur la liste des b\u00e9n\u00e9ficiaires ;\u00a0se sont dirig\u00e9es vers le centre culturel de la ville o\u00f9 est install\u00e9 le bureau des recours.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Arzew en \u00e9bullition<\/h2>\n\n\n\n<p>D\u2019ailleurs, certains revendicateurs ont tenu \u00e0 mettre en relief que des <a href=\"https:\/\/www.facebook.com\/lkeriacom\/\">personnes<\/a>, venant de diff\u00e9rents horizons qui ont enfreint la loi par des constructions illicites dans l\u2019espace public, ont \u00ab forc\u00e9 la main \u00bb de la commission par cet acte ill\u00e9gal pour se voir attribuer un logement, alors que d\u2019autres, dignes et honn\u00eates, ne pouvant pas commettre le m\u00eame \u00ab d\u00e9lit \u00bb, habitent en sous location \u00e0 des prix qui \u00abavalent\u00bb toutes leurs mensualit\u00e9s, attendent toujours apr\u00e8s le d\u00e9p\u00f4t de leurs dossiers.<\/p>\n\n\n\n<p>Sollicit\u00e9, un responsable du bureau des recours nous fera part \u00ab nous avons enregistr\u00e9 plus de 80 recours et cela ; uniquement avant midi de la matin\u00e9e d\u2019hier\u00bb.\u00a0Ajoutant \u00ab de toutes fa\u00e7ons, les d\u00e9lais de recours sont ouverts pendant huit jours \u00bb. <\/p>\n\n\n\n<p>Par ailleurs, nous avons appris, par notre source, que le <a href=\"https:\/\/www.lkeria.com\/annonces\/immobilier\/vente\/terrain\">choix du terrain <\/a>pour un autre quota de 2000 logements ; rentrant toujours dans le cadre du programme social, est en cours de n\u00e9gociation avec les services de l\u2019agriculture ; qui ont octroy\u00e9, pour la construction de cette tranche, une assiette de cinq hectares \u00e0 Hai Gourine ; alors qu\u2019elle n\u00e9cessite une superficie de 15 hectares. Enfin, dans une vision optimiste, notre source a tenu \u00e0 rassurer les sans logis d\u2019Arzew qu\u2019avec les programmes de 2000 logements, du LPA (900 unit\u00e9s), de l\u2019AADL et de la promotionnelle de la CNEP, les 10.000 d\u00e9pos\u00e9es, apr\u00e8s leur traitement et assainissement, la crise du logement sera tr\u00e8s att\u00e9nu\u00e9e \u00e0 Arzew pour ne pas dire\u00a0 compl\u00e8tement g\u00e9r\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ville d\u2019Arzew \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux. C\u2019\u00e9tait le sujet principal de toute discussion entre les citoyens, notamment ceux ; qui ont d\u00e9pos\u00e9 des dossiers pour pr\u00e9tendre \u00e0 un toit d\u00e9cent dans le cadre du programme au relogement social. Selon certaines [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229],"tags":[],"class_list":["post-4966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-logement"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie<\/title>\n<meta name=\"description\" content=\"La ville d\u2019Arzew \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie\" \/>\n<meta property=\"og:description\" content=\"La ville d\u2019Arzew \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/\" \/>\n<meta property=\"og:site_name\" content=\"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lkeriacom\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-04T17:44:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-25T18:03:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2013\/01\/Arzew-en-ebullition-affichage-liste-beneficiaires-logements.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lotfi Ramdani\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lkeriacom\" \/>\n<meta name=\"twitter:site\" content=\"@lkeriacom\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lotfi Ramdani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","description":"La ville d\u2019Arzew \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/","og_locale":"fr_FR","og_type":"article","og_title":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","og_description":"La ville d\u2019Arzew \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux","og_url":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/","og_site_name":"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","article_publisher":"https:\/\/www.facebook.com\/lkeriacom","article_published_time":"2013-01-04T17:44:06+00:00","article_modified_time":"2021-09-25T18:03:11+00:00","og_image":[{"width":620,"height":381,"url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2013\/01\/Arzew-en-ebullition-affichage-liste-beneficiaires-logements.jpg","type":"image\/jpeg"}],"author":"Lotfi Ramdani","twitter_card":"summary_large_image","twitter_creator":"@lkeriacom","twitter_site":"@lkeriacom","twitter_misc":{"\u00c9crit par":"Lotfi Ramdani","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#article","isPartOf":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/"},"author":{"name":"Lotfi Ramdani","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/person\/3a4da2e91b49098351a6c1a04c231e06"},"headline":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements","datePublished":"2013-01-04T17:44:06+00:00","dateModified":"2021-09-25T18:03:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/"},"wordCount":583,"publisher":{"@id":"https:\/\/www.lkeria.com\/actualites\/#organization"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2013\/01\/Arzew-en-ebullition-affichage-liste-beneficiaires-logements.jpg","articleSection":["Logement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/","url":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/","name":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements - Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","isPartOf":{"@id":"https:\/\/www.lkeria.com\/actualites\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#primaryimage"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2013\/01\/Arzew-en-ebullition-affichage-liste-beneficiaires-logements.jpg","datePublished":"2013-01-04T17:44:06+00:00","dateModified":"2021-09-25T18:03:11+00:00","description":"La ville d\u2019Arzew \u00e9tait, hier, en \u00e9bullition \u00e0 la suite de l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires des 1300 logements sociaux","breadcrumb":{"@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#primaryimage","url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2013\/01\/Arzew-en-ebullition-affichage-liste-beneficiaires-logements.jpg","contentUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2013\/01\/Arzew-en-ebullition-affichage-liste-beneficiaires-logements.jpg","width":620,"height":381,"caption":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lkeria.com\/actualites\/logement\/arzew-apres-laffichage-de-la-liste-des-beneficiaires-des-1300-logements-sociaux-la-ville-en-ebullition\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lkeria.com\/actualites\/"},{"@type":"ListItem","position":2,"name":"Arzew en \u00e9bullition apr\u00e8s l\u2019affichage de la liste des b\u00e9n\u00e9ficiaires de logements"}]},{"@type":"WebSite","@id":"https:\/\/www.lkeria.com\/actualites\/#website","url":"https:\/\/www.lkeria.com\/actualites\/","name":"Actualit\u00e9 de l&#039;immobilier et le logement en Alg\u00e9rie","description":"logement et annonces immobili\u00e8res","publisher":{"@id":"https:\/\/www.lkeria.com\/actualites\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lkeria.com\/actualites\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lkeria.com\/actualites\/#organization","name":"Lkeria","url":"https:\/\/www.lkeria.com\/actualites\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/logo\/image\/","url":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2020\/07\/logo-lkeria.png","contentUrl":"https:\/\/www.lkeria.com\/actualites\/wp-content\/uploads\/2020\/07\/logo-lkeria.png","width":200,"height":72,"caption":"Lkeria"},"image":{"@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lkeriacom","https:\/\/x.com\/lkeriacom"]},{"@type":"Person","@id":"https:\/\/www.lkeria.com\/actualites\/#\/schema\/person\/3a4da2e91b49098351a6c1a04c231e06","name":"Lotfi Ramdani","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/769db425c6f465158149f1ffd6cf61ce7a8a879d11dfbef8288af36dfddd418c?s=96&d=mm&r=g","caption":"Lotfi Ramdani"},"url":"https:\/\/www.lkeria.com\/actualites\/author\/chakib32gmail-com\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/4966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/comments?post=4966"}],"version-history":[{"count":3,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/4966\/revisions"}],"predecessor-version":[{"id":5837,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/posts\/4966\/revisions\/5837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/media\/5836"}],"wp:attachment":[{"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/media?parent=4966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/categories?post=4966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lkeria.com\/actualites\/wp-json\/wp\/v2\/tags?post=4966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}